{"id":15356,"date":"2022-01-17T11:56:41","date_gmt":"2022-01-17T14:56:41","guid":{"rendered":"https:\/\/www.casadainjecao.com.br\/loja\/?post_type=product&#038;p=15356"},"modified":"2026-02-06T11:44:12","modified_gmt":"2026-02-06T14:44:12","slug":"suporte-sensor-de-velocidade-renault-duster-479608353r","status":"publish","type":"product","link":"https:\/\/www.casadainjecao.com.br\/loja\/autopecas\/injecao-eletronica\/sensores-injecao-eletronica\/suporte-sensor-de-velocidade-renault-duster-479608353r\/","title":{"rendered":"Suporte Sensor de Velocidade Renault Duster &#8211; 47960835"},"content":{"rendered":"<h1>Suporte Sensor de Velocidade Renault Duster &#8211; 479608353R<\/h1>\n","protected":false},"excerpt":{"rendered":"<h2 class=\"QN2lPu\">Suporte Sensor de Velocidade Renault Duster<\/h2>\n<h3 class=\"QN2lPu\">Compat\u00edvel com Renault Duster (com ABS e sensores de velocidade)<\/h3>\n<h3 class=\"QN2lPu\">Renault Duster &#8211; 2011 2012 2013 2014 2015 2016 2017 2018 (1\u00aa gera\u00e7\u00e3o \u2014 sistema de freio com sensores de velocidade dianteiros)<\/h3>\n<h3 class=\"QN2lPu\"><\/h3>\n<h3 class=\"QN2lPu\">Codigo:- 479608353R<\/h3>\n<h3 class=\"QN2lPu\"><\/h3>\n<h3 class=\"QN2lPu\"><\/h3>\n<h3 class=\"QN2lPu\">Condi\u00e7\u00e3o do item: Novo<\/h3>\n<h3 class=\"QN2lPu\"><\/h3>\n<h3 class=\"QN2lPu\">Marca: Renault<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"QN2lPu\"><\/h3>\n<p class=\"QN2lPu\">garantia: 3 meses<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"QN2lPu\">ATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalado no seu ve\u00edculo. e confirme se corresponde ao c\u00f3digo informado neste an\u00fancio.<\/p>\n<p class=\"QN2lPu\">Em caso de d\u00favida, utilize o campo de perguntas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"QN2lPu\">Essa pe\u00e7a faz parte do sistema ABS \/ sensor de velocidade das rodas do Renault Duster.<\/p>\n<p class=\"QN2lPu\">Ela aparece nos esquemas de pe\u00e7as dos cat\u00e1logos de ABS do Duster em diferentes anos e motores,<\/p>\n<p class=\"QN2lPu\">indicando que o suporte \u00e9 usado para fixar o sensor de velocidade da roda no cubo\/suspens\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A Casa da Inje\u00e7\u00e3o oferece total garantia nos produtos comprados em nosso site.<br \/>\nCada item \u00e9 rigorosamente testado antes do envio<br \/>\nSe os itens estiverem danificados ou parcialmente defeituosos, entre em contato conosco.<br \/>\nProcure um profissional devidamente licenciado para a instala\u00e7\u00e3o e fa\u00e7a revis\u00f5es periodicamente. A empresa n\u00e3o se responsabiliza por problemas oriundos da m\u00e1 instala\u00e7\u00e3o ou com a falta de cuidados peri\u00f3dicos dos componentes.<br \/>\nSe houver qualquer defeito, n\u00f3s lhe enviaremos uma substitui\u00e7\u00e3o ap\u00f3s receber o pacote ou devolvemos seu dinheiro.<br \/>\nLeia nossa pol\u00edtica de devolu\u00e7\u00e3o aqui<br \/>\nTem alguma d\u00favida?<br \/>\nEntre em contato que podemos ajudar!<br \/>\nConfira as informa\u00e7\u00f5es adicionais abaixo:<br \/>\nTodos os nossos produtos s\u00e3o novos, semi-novos, originais e paralelos possuem garantia.<br \/>\nTodos os produtos anunciados est\u00e3o dispon\u00edveis em estoque e s\u00e3o enviados com extrema rapidez.<br \/>\nO frete pode ser simulado antes de efetuar a compra, basta clicar em \u201cver custos de envio\u201d.<br \/>\nVerifique o endere\u00e7o de entrega cadastrado e atualize caso necess\u00e1rio.<br \/>\nConfirme se a pe\u00e7a \u00e9 correta para o seu modelo de ve\u00edculo.<br \/>\nPara pe\u00e7as automotivas, recomendamos a instala\u00e7\u00e3o por um profissional especializado.<br \/>\nCaso possua outras d\u00favidas, entre em contato.<\/p>\n","protected":false},"featured_media":15360,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_joinchat":[]},"product_brand":[],"product_cat":[21,22,269,242],"product_tag":[52],"berocket_brand":[394],"class_list":{"0":"post-15356","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-injecao-eletronica","7":"product_cat-motor","8":"product_cat-sensores-injecao-eletronica","9":"product_cat-suporte","10":"product_tag-duster","11":"berocket_brand-renault","12":"thunk-woo-product-list","13":"big-store-woo-hover-zoom","14":"open-single-product-tab-horizontal","15":"open-shadow-","16":"open-shadow-hover-","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"taxonomy_info":{"product_cat":[{"value":21,"label":"Inje\u00e7\u00e3o Eletr\u00f4nica"},{"value":22,"label":"Motor"},{"value":269,"label":"Sensores"},{"value":242,"label":"Suporte"}],"product_tag":[{"value":52,"label":"Duster"}],"berocket_brand":[{"value":394,"label":"Renault"}]},"featured_image_src_large":["https:\/\/www.casadainjecao.com.br\/loja\/wp-content\/uploads\/2022\/01\/479608353r-Suporte-Sensor-de-Velocidade-Renault-Duster-original-653x780.jpg",640,764,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product\/15356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media\/15360"}],"wp:attachment":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media?parent=15356"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=15356"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=15356"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=15356"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/berocket_brand?post=15356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}