{"id":23946,"date":"2023-03-31T16:38:05","date_gmt":"2023-03-31T19:38:05","guid":{"rendered":"https:\/\/www.casadainjecao.com.br\/loja\/?post_type=product&#038;p=23946"},"modified":"2026-07-08T16:01:56","modified_gmt":"2026-07-08T19:01:56","slug":"kit-4x-bico-injetor-x60-lifan-2017-0280156299","status":"publish","type":"product","link":"https:\/\/www.casadainjecao.com.br\/loja\/autopecas\/injecao-eletronica\/bico-injetor\/kit-4x-bico-injetor-x60-lifan-2017-0280156299\/","title":{"rendered":"Kit 4X Bico Injetor X60 Lifan 2017 &#8211; 0280156299"},"content":{"rendered":"<h2 class=\"ui-pdp-title\">Kit 4 Bicos Injetores<\/h2>\n<h3 class=\"ui-pdp-title\">Lifan X60 2017 a 2018<\/h3>\n<h3 class=\"ui-pdp-title\">C\u00f3digo de Refer\u00eancia:<\/h3>\n<h3 class=\"ui-pdp-title\">0280156299, 06J906262K<\/h3>\n<p>Condi\u00e7\u00f5es:<br \/>\nProduto Novo \/ Marca Torken<br \/>\nGarantia:<br \/>\n3 Meses<br \/>\nATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalado no seu ve\u00edculo.<\/p>\n<p>Condi\u00e7\u00f5es:<br \/>\nProduto Novo \/ Marca Torken<br \/>\nGarantia:<br \/>\n3 Meses<br \/>\nATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalado no seu ve\u00edculo.<br \/>\nA Casa da Inje\u00e7\u00e3o SP oferece total garantia nos produtos comprados em nosso site.<br \/>\nCada item \u00e9 rigorosamente inspecionado\u00a0antes do envio<br \/>\nSe os itens estiverem danificados ou parcialmente defeituosos, entre em contato conosco.<br \/>\nProcure um profissional devidamente licenciado para a instala\u00e7\u00e3o e fa\u00e7a revis\u00f5es periodicamente. A empresa n\u00e3o se responsabiliza por problemas oriundos da m\u00e1 instala\u00e7\u00e3o ou com a falta de cuidados peri\u00f3dicos dos componentes.<br \/>\nSe houver qualquer defeito, ficamos a disposi\u00e7\u00e3o para a substitui\u00e7\u00e3o ou devolvemos seu dinheiro.<br \/>\nTem alguma d\u00favida?<br \/>\nEntre em contato que podemos ajudar!<br \/>\nConfira as informa\u00e7\u00f5es adicionais abaixo:<br \/>\nTodos os produtos anunciados est\u00e3o dispon\u00edveis em estoque e s\u00e3o enviados com extrema rapidez .<br \/>\nO frete pode ser simulado antes de efetuar a compra, basta clicar em \u201cver custos de envio\u201d.<br \/>\nVerifique o endere\u00e7o de entrega cadastrado e atualize caso necess\u00e1rio.<br \/>\nConfirme se a pe\u00e7a \u00e9 correta para o seu modelo de ve\u00edculo.<br \/>\nPara pe\u00e7as automotivas, recomendamos a instala\u00e7\u00e3o por um profissional especializado.<br \/>\nCaso possua outras d\u00favidas, entre em contato.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2 class=\"ui-pdp-title\">Kit 4X Bico Injetor X60 Lifan 2017 &#8211; 0280156299<\/h2>\n<h2><\/h2>\n","protected":false},"featured_media":23947,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_kb_optimizer_status":0,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_joinchat":[]},"product_brand":[],"product_cat":[256,21],"product_tag":[1797],"berocket_brand":[1796],"class_list":{"0":"post-23946","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bico-injetor","7":"product_cat-injecao-eletronica","8":"product_tag-x60-lifan","9":"berocket_brand-lifan","10":"thunk-woo-product-list","11":"big-store-woo-hover-zoom","12":"open-single-product-tab-horizontal","13":"open-shadow-","14":"open-shadow-hover-","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"taxonomy_info":{"product_cat":[{"value":256,"label":"Bico Injetor"},{"value":21,"label":"Inje\u00e7\u00e3o Eletr\u00f4nica"}],"product_tag":[{"value":1797,"label":"X60 Lifan"}],"berocket_brand":[{"value":1796,"label":"Lifan"}]},"featured_image_src_large":["https:\/\/www.casadainjecao.com.br\/loja\/wp-content\/uploads\/2023\/03\/cats-52-900x680.jpg",640,484,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product\/23946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media\/23947"}],"wp:attachment":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media?parent=23946"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=23946"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=23946"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=23946"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/berocket_brand?post=23946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}