{"id":36852,"date":"2024-10-10T13:49:31","date_gmt":"2024-10-10T16:49:31","guid":{"rendered":"https:\/\/www.casadainjecao.com.br\/loja\/?post_type=product&#038;p=36852"},"modified":"2026-05-12T14:06:44","modified_gmt":"2026-05-12T17:06:44","slug":"copo-bomba-de-combustivel-com-filtro-renault-logan-sandero-8200616585","status":"publish","type":"product","link":"https:\/\/www.casadainjecao.com.br\/loja\/autopecas\/injecao-eletronica\/bomba-de-combustivel\/copo-bomba-de-combustivel-com-filtro-renault-logan-sandero-8200616585\/","title":{"rendered":"Copo Bomba de Combustivel com Filtro Renault Logan Sandero &"},"content":{"rendered":"<h1>Copo Bomba de Combustivel com Filtro Novo Original<\/h1>\n<h3>Logan 1.6 4cil 8v 2007&gt;2014<br \/>\nLogan 1.6 4cil 16v 2007&gt;2009<br \/>\nSandero 1.0 4cil 16v 2013&gt;2014<\/h3>\n<h3>Codigo:- 8200616585,172029382r,172024388r,6001547604,MD213186RE, DS26104, VP068<\/h3>\n<h5><strong>Condi\u00e7\u00f5es:<\/strong><\/h5>\n<h5><strong>Produto Novo Original<\/strong><\/h5>\n<h5><strong>Garantia:<\/strong><\/h5>\n<h5><strong>3 Meses<\/strong><\/h5>\n<h5><strong>ATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalado no seu ve\u00edculo.<\/strong><\/h5>\n<h5><strong>A Casa da Inje\u00e7\u00e3o oferece total garantia nos produtos comprados em nosso site.<\/strong><\/h5>\n<h5><strong>Cada item \u00e9 rigorosamente testado antes do envio<\/strong><\/h5>\n<h5><strong>Se os itens estiverem danificados ou parcialmente defeituosos, entre em contato conosco.<\/strong><\/h5>\n<h5><strong>Procure um profissional devidamente licenciado para a instala\u00e7\u00e3o e fa\u00e7a revis\u00f5es periodicamente. A empresa n\u00e3o se responsabiliza por problemas oriundos da m\u00e1 instala\u00e7\u00e3o ou com a falta de cuidados peri\u00f3dicos dos componentes.<\/strong><\/h5>\n<h5><strong>Se houver qualquer defeito, n\u00f3s lhe enviaremos uma substitui\u00e7\u00e3o ap\u00f3s receber o pacote ou devolvemos seu dinheiro.<\/strong><\/h5>\n<h5><strong>Leia nossa\u00a0<\/strong><a href=\"https:\/\/www.casadainjecao.com.br\/loja\/politica-de-devolucao\"><strong>pol\u00edtica de devolu\u00e7\u00e3o aqui<\/strong><\/a><\/h5>\n<h5><strong>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013<\/strong><\/h5>\n<h5><strong>Tem alguma d\u00favida?<\/strong><\/h5>\n<h5><strong>Entre em contato que podemos ajudar!<\/strong><\/h5>\n<h5><strong>Confira as informa\u00e7\u00f5es adicionais abaixo:<\/strong><\/h5>\n<h5><strong>Todos os nossos produtos s\u00e3o novos, semi-novos, originais e paralelos possuem garantia.<\/strong><\/h5>\n<h5><strong>Todos os produtos anunciados est\u00e3o dispon\u00edveis em estoque e s\u00e3o enviados com extrema rapidez.<\/strong><\/h5>\n<h5><strong>O frete pode ser simulado antes de efetuar a compra, basta clicar em \u201cver custos de envio\u201d.<\/strong><\/h5>\n<h5><strong>Verifique o endere\u00e7o de entrega cadastrado e atualize caso necess\u00e1rio.<\/strong><\/h5>\n<h5><strong>Confirme se a pe\u00e7a \u00e9 correta para o seu modelo de ve\u00edculo.<\/strong><\/h5>\n<h5><strong>Para pe\u00e7as automotivas, recomendamos a instala\u00e7\u00e3o por um profissional especializado.<\/strong><\/h5>\n<h5><strong>Caso possua outras d\u00favidas, entre em contato.<\/strong><\/h5>\n","protected":false},"excerpt":{"rendered":"<h2>Copo Bomba de Combustivel com Filtro Renault Logan Sandero &#8211; 8200616585<\/h2>\n","protected":false},"featured_media":36958,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_joinchat":[]},"product_brand":[],"product_cat":[257,260,21],"product_tag":[66,91],"berocket_brand":[394],"class_list":{"0":"post-36852","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bomba-de-combustivel","7":"product_cat-filtro-de-combustivel","8":"product_cat-injecao-eletronica","9":"product_tag-logan","10":"product_tag-sandero","11":"berocket_brand-renault","12":"thunk-woo-product-list","13":"big-store-woo-hover-zoom","14":"open-single-product-tab-horizontal","15":"open-shadow-","16":"open-shadow-hover-","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"taxonomy_info":{"product_cat":[{"value":257,"label":"Bomba de Combustivel"},{"value":260,"label":"Filtro de Combustivel"},{"value":21,"label":"Inje\u00e7\u00e3o Eletr\u00f4nica"}],"product_tag":[{"value":66,"label":"Logan"},{"value":91,"label":"Sandero"}],"berocket_brand":[{"value":394,"label":"Renault"}]},"featured_image_src_large":["https:\/\/www.casadainjecao.com.br\/loja\/wp-content\/uploads\/2024\/10\/Copo-Bomba-de-Combustivel-com-Filtro-Renault-Logan-Sandero-ORIGINAL-8200616585-920x920.jpg",640,640,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product\/36852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media\/36958"}],"wp:attachment":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media?parent=36852"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=36852"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=36852"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=36852"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/berocket_brand?post=36852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}