{"id":39752,"date":"2025-04-17T09:11:45","date_gmt":"2025-04-17T12:11:45","guid":{"rendered":"https:\/\/www.casadainjecao.com.br\/loja\/?post_type=product&#038;p=39752"},"modified":"2025-05-15T11:31:34","modified_gmt":"2025-05-15T14:31:34","slug":"resistencia-caixa-de-ar-fiat-stilo-punto-507730700","status":"publish","type":"product","link":"https:\/\/www.casadainjecao.com.br\/loja\/autopecas\/ar-condicionado\/resistencia\/resistencia-caixa-de-ar-fiat-stilo-punto-507730700\/","title":{"rendered":"Resistencia Caixa De Ar Fiat Stilo Punto -507730700"},"content":{"rendered":"<h2>Resistencia Caixa De Ar<\/h2>\n<p>GM Agile<\/p>\n<p>Fiat Stilo <span style=\"font-size: 16px;\">2003 a 2004<\/span><\/p>\n<p>Fiat Punto 2013 a 2015<\/p>\n<p>Punto Attractive 1.4 l 16V 2014 a 2017<\/p>\n<p>Punto Attractive 1.4 l 8V 2010 a 2012<\/p>\n<p>Punto Blackmotion 1.8 l 16V 2013 a 2017<\/p>\n<p>Punto Blackmotion Dualogic 1.8 l 16V 2016 a 2017<\/p>\n<p>Punto Essence 1.6 l 16V 2010 a 2012<\/p>\n<p>Punto Essence 1.8 l 16V 2010 a 2012<\/p>\n<p>Punto Essence Dual 1.6 l 16V 2010 a 2012)<\/p>\n<p>Punto Essence Dual 1.8 l 16V 2010 a 2012<\/p>\n<p>Punto Essence Dualogic 1.6 l 16V 2016 a 2017<\/p>\n<p>Punto Essence 5P 1.6 l 16V 2014 a 2017<\/p>\n<p>Punto It\u00e1lia 1.4 l 8V 2014 a 2017<\/p>\n<p>Punto Sporting 1.8 l 16V 2010 a 2012<\/p>\n<p>Punto Sporting 1.8 l 16V 2014 a 2016<\/p>\n<p>Punto Sporting Dualogic 1.8 l 16V 2010 a 2012<\/p>\n<p>Punto T-Jet 1.4 l 16V 2014 a 2016<\/p>\n<h4>C\u00f3digo de Refer\u00eancia:<\/h4>\n<p>507730700<\/p>\n<h4>C\u00f3digo Equivalente:<\/h4>\n<p>A51002901 l 7078695 (FIAT)<\/p>\n<p>94731446 l 94753866 (CHEVROLET)<\/p>\n<p>PPWA123 l 377959493B (VOLKSWAGEN)<\/p>\n<p>RC.420.017<\/p>\n<p>FIAT: 7.078.695 \/ 96.03251 \/ 390403251<\/p>\n<p>EATON: MMC 0702 \/ MMC0910<\/p>\n<p>7.078.695<\/p>\n<p>DELPHI: WC1031<\/p>\n<h4><strong>Condi\u00e7\u00f5es:<\/strong><\/h4>\n<p>Produto Novo \/ Marca Torken<\/p>\n<h4><strong>Garantia:<\/strong><\/h4>\n<p>3 Meses<\/p>\n<h3><strong>ATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalada no seu ve\u00edculo.<\/strong><\/h3>\n<h5><\/h5>\n<p>A Casa da Inje\u00e7\u00e3o oferece total garantia nos produtos comprados em nosso site.<\/p>\n<p>Cada item \u00e9 rigorosamente testado antes do envio<\/p>\n<p>Se os itens estiverem danificados ou parcialmente defeituosos, entre em contato conosco.<\/p>\n<p>Procure um profissional devidamente licenciado para a instala\u00e7\u00e3o e fa\u00e7a revis\u00f5es periodicamente. A empresa n\u00e3o se responsabiliza por problemas oriundos da m\u00e1 instala\u00e7\u00e3o ou com a falta de cuidados peri\u00f3dicos dos componentes.<\/p>\n<p>Se houver qualquer defeito, n\u00f3s lhe enviaremos uma substitui\u00e7\u00e3o ap\u00f3s receber o pacote ou devolvemos seu dinheiro.<\/p>\n<p>Leia nossa\u00a0<a href=\"https:\/\/www.casadainjecao.com.br\/loja\/politica-de-devolucao\">pol\u00edtica de devolu\u00e7\u00e3o aqui<\/a><\/p>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2013<\/p>\n<p>Tem alguma d\u00favida?<\/p>\n<p>Entre em contato que podemos ajudar!<\/p>\n<p>Confira as informa\u00e7\u00f5es adicionais abaixo:<\/p>\n<p>Todos os nossos produtos s\u00e3o novos, semi-novos, originais e paralelos possuem garantia.<\/p>\n<p>Todos os produtos anunciados est\u00e3o dispon\u00edveis em estoque e s\u00e3o enviados com extrema rapidez.<\/p>\n<p>O frete pode ser simulado antes de efetuar a compra, basta clicar em \u201cver custos de envio\u201d.<\/p>\n<p>Verifique o endere\u00e7o de entrega cadastrado e atualize caso necess\u00e1rio.<\/p>\n<p>Confirme se a pe\u00e7a \u00e9 correta para o seu modelo de ve\u00edculo.<\/p>\n<p>Para pe\u00e7as automotivas, recomendamos a instala\u00e7\u00e3o por um profissional especializado.<\/p>\n<p>Caso possua outras d\u00favidas, entre em contato.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Resistencia Caixa De Ar Fiat Stilo Punto GM Agile &#8211; 507730700<\/h2>\n","protected":false},"featured_media":39755,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_joinchat":[]},"product_brand":[],"product_cat":[16,79],"product_tag":[1410,108,1613],"berocket_brand":[381,383],"class_list":{"0":"post-39752","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ar-condicionado","7":"product_cat-resistencia","8":"product_tag-agile","9":"product_tag-punto","10":"product_tag-stilo","11":"berocket_brand-chevrolet","12":"berocket_brand-fiat","13":"thunk-woo-product-list","14":"big-store-woo-hover-zoom","15":"open-single-product-tab-horizontal","16":"open-shadow-","17":"open-shadow-hover-","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"taxonomy_info":{"product_cat":[{"value":16,"label":"Ar Condicionado"},{"value":79,"label":"Resistencia"}],"product_tag":[{"value":1410,"label":"AGile"},{"value":108,"label":"Punto"},{"value":1613,"label":"Stilo"}],"berocket_brand":[{"value":381,"label":"Chevrolet"},{"value":383,"label":"Fiat"}]},"featured_image_src_large":["https:\/\/www.casadainjecao.com.br\/loja\/wp-content\/uploads\/2025\/04\/Resistencia-Caixa-De-Ar-Fiat-Stilo-original-507730700-920x920.jpg",640,640,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product\/39752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media\/39755"}],"wp:attachment":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media?parent=39752"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=39752"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=39752"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=39752"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/berocket_brand?post=39752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}