{"id":42539,"date":"2025-11-26T17:15:34","date_gmt":"2025-11-26T20:15:34","guid":{"rendered":"https:\/\/www.casadainjecao.com.br\/loja\/?post_type=product&#038;p=42539"},"modified":"2026-08-29T21:48:49","modified_gmt":"2026-08-30T00:48:49","slug":"par-rele-auxiliar-cinza-4-terminais-corolla-etios-9008087021-copia","status":"publish","type":"product","link":"https:\/\/www.casadainjecao.com.br\/loja\/autopecas\/eletrica\/reles\/par-rele-auxiliar-cinza-4-terminais-corolla-etios-9008087021-copia\/","title":{"rendered":"Par Rel\u00e9 Auxiliar Cinza 4 Terminais Corolla Etios 9008087021 (c\u00f3pia)"},"content":{"rendered":"<h1>Par Rele Auxiliar 4 Terminais<\/h1>\n<h3>TOYOTA<\/h3>\n<h3>COROLLA 1.8 2.0\u00a02014 A 2018<\/h3>\n<h3>ETIOS<\/h3>\n<h3>C\u00f3digo de Refer\u00eancia:<\/h3>\n<h3>9008087021, 90080-87021<\/h3>\n<h5><strong>Condi\u00e7\u00f5es:<\/strong><\/h5>\n<h5><strong>Produto Novo Original \/ Marca Torken<\/strong><\/h5>\n<h5>Especifica\u00e7\u00f5es:<\/h5>\n<p>valor referente a 2 rel\u00e9s<\/p>\n<h5><strong>Garantia:<\/strong><\/h5>\n<h5><strong>3 Meses<\/strong><\/h5>\n<h5><strong>ATEN\u00c7\u00c3O: Antes de efetuar a compra verifique o c\u00f3digo da sua pe\u00e7a que est\u00e1 instalado no seu ve\u00edculo.<\/strong><\/h5>\n<h5><strong>A Casa da Inje\u00e7\u00e3o oferece total garantia nos produtos comprados em nosso site.<\/strong><\/h5>\n<h5><strong>Cada item \u00e9 rigorosamente testado antes do envio<\/strong><\/h5>\n<h5><strong>Se os itens estiverem danificados ou parcialmente defeituosos, entre em contato conosco.<\/strong><\/h5>\n<h5><strong>Procure um profissional devidamente licenciado para a instala\u00e7\u00e3o e fa\u00e7a revis\u00f5es periodicamente. A empresa n\u00e3o se responsabiliza por problemas oriundos da m\u00e1 instala\u00e7\u00e3o ou com a falta de cuidados peri\u00f3dicos dos componentes.<\/strong><\/h5>\n<h5><strong>Se houver qualquer defeito, n\u00f3s lhe enviaremos uma substitui\u00e7\u00e3o ap\u00f3s receber o pacote ou devolvemos seu dinheiro.<\/strong><\/h5>\n<h5><strong>Leia nossa\u00a0<\/strong><a href=\"https:\/\/www.casadainjecao.com.br\/loja\/politica-de-devolucao\"><strong>pol\u00edtica de devolu\u00e7\u00e3o aqui<\/strong><\/a><\/h5>\n<h5><strong>Tem alguma d\u00favida?<\/strong><\/h5>\n<h5><strong>Entre em contato que podemos ajudar!<\/strong><\/h5>\n<h5><strong>Confira as informa\u00e7\u00f5es adicionais abaixo:<\/strong><\/h5>\n<h5><strong>Todos os nossos produtos s\u00e3o novos, semi-novos, originais e paralelos possuem garantia.<\/strong><\/h5>\n<h5><strong>Todos os produtos anunciados est\u00e3o dispon\u00edveis em estoque e s\u00e3o enviados com extrema rapidez.<\/strong><\/h5>\n<h5><strong>O frete pode ser simulado antes de efetuar a compra, basta clicar em \u201cver custos de envio\u201d.<\/strong><\/h5>\n<h5><strong>Verifique o endere\u00e7o de entrega cadastrado e atualize caso necess\u00e1rio.<\/strong><\/h5>\n<h5><strong>Confirme se a pe\u00e7a \u00e9 correta para o seu modelo de ve\u00edculo.<\/strong><\/h5>\n<h5><strong>Para pe\u00e7as automotivas, recomendamos a instala\u00e7\u00e3o por um profissional especializado.<\/strong><\/h5>\n<h5><strong>Caso possua outras d\u00favidas, entre em contato.<\/strong><\/h5>\n","protected":false},"excerpt":{"rendered":"<h2>Par Rel\u00e9 Auxiliar Cinza 4 Terminais Corolla Etios 9008087021<\/h2>\n","protected":false},"featured_media":50122,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_kb_optimizer_status":0,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[]},"product_brand":[],"product_cat":[17,153],"product_tag":[850,1368],"berocket_brand":[395],"class_list":{"0":"post-42539","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-eletrica","7":"product_cat-reles","8":"product_tag-corolla","9":"product_tag-etios","10":"berocket_brand-toyota","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple","19":"entry","20":"content-bg","21":"loop-entry"},"taxonomy_info":{"product_cat":[{"value":17,"label":"El\u00e9trica"},{"value":153,"label":"Reles"}],"product_tag":[{"value":850,"label":"Corolla"},{"value":1368,"label":"Etios"}],"berocket_brand":[{"value":395,"label":"Toyota"}]},"featured_image_src_large":["https:\/\/www.casadainjecao.com.br\/loja\/wp-content\/uploads\/2026\/08\/Copia-de-Copia-de-Copia-de-Copia-de-CRIATIVO-REFERENCIA-CIEBR-2025-11-26T171711.986-2-q-920x920.jpg",920,920,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product\/42539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media\/50122"}],"wp:attachment":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/media?parent=42539"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_brand?post=42539"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=42539"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=42539"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/berocket_brand?post=42539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}