{"id":1124,"count":9,"description":"","link":"https:\/\/www.casadainjecao.com.br\/loja\/categoria-autopecas\/interior\/porta-luvas\/","name":"Porta Luvas","slug":"porta-luvas","taxonomy":"product_cat","parent":24,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat\/1124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product_cat\/24"}],"wp:post_type":[{"href":"https:\/\/www.casadainjecao.com.br\/loja\/wp-json\/wp\/v2\/product?product_cat=1124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}